{"id":3955,"date":"2017-04-20T18:07:08","date_gmt":"2017-04-20T16:07:08","guid":{"rendered":"http:\/\/www.c-intereg.es\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/"},"modified":"2017-04-20T18:07:08","modified_gmt":"2017-04-20T16:07:08","slug":"cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta","status":"publish","type":"post","link":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/","title":{"rendered":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"link","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[69],"tags":[],"class_list":{"0":"post-3955","1":"post","2":"type-post","3":"status-publish","4":"format-link","6":"category-briefings","7":"post_format-post-format-link"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\" \/>\n<meta property=\"og:site_name\" content=\"C-Intereg\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-20T16:07:08+00:00\" \/>\n<meta name=\"author\" content=\"C-Intereg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"C-Intereg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\"},\"author\":{\"name\":\"C-Intereg\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\"},\"headline\":\"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA\",\"datePublished\":\"2017-04-20T16:07:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\"},\"wordCount\":11,\"commentCount\":0,\"articleSection\":[\"Briefings\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\",\"url\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\",\"name\":\"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg\",\"isPartOf\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/#website\"},\"datePublished\":\"2017-04-20T16:07:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.c-intereg.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#website\",\"url\":\"https:\/\/www.c-intereg.es\/en\/\",\"name\":\"C-Intereg\",\"description\":\"An\u00e1lisis del comercio interregional espa\u00f1ol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.c-intereg.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\",\"name\":\"C-Intereg\",\"url\":\"https:\/\/www.c-intereg.es\/en\/author\/interbanner-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/","og_locale":"en_US","og_type":"article","og_title":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg","og_url":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/","og_site_name":"C-Intereg","article_published_time":"2017-04-20T16:07:08+00:00","author":"C-Intereg","twitter_card":"summary_large_image","twitter_misc":{"Written by":"C-Intereg"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#article","isPartOf":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/"},"author":{"name":"C-Intereg","@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355"},"headline":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA","datePublished":"2017-04-20T16:07:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/"},"wordCount":11,"commentCount":0,"articleSection":["Briefings"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/","url":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/","name":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA - C-Intereg","isPartOf":{"@id":"https:\/\/www.c-intereg.es\/en\/#website"},"datePublished":"2017-04-20T16:07:08+00:00","author":{"@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355"},"breadcrumb":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-la-exposicion-de-las-comunidades-autonomas-al-ceta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.c-intereg.es\/en\/"},{"@type":"ListItem","position":2,"name":"Cuadro. La exposici\u00f3n de las comunidades aut\u00f3nomas al CETA"}]},{"@type":"WebSite","@id":"https:\/\/www.c-intereg.es\/en\/#website","url":"https:\/\/www.c-intereg.es\/en\/","name":"C-Intereg","description":"An\u00e1lisis del comercio interregional espa\u00f1ol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.c-intereg.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355","name":"C-Intereg","url":"https:\/\/www.c-intereg.es\/en\/author\/interbanner-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts\/3955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/comments?post=3955"}],"version-history":[{"count":0,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts\/3955\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/media?parent=3955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/categories?post=3955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/tags?post=3955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}