{"id":3933,"date":"2018-10-07T17:48:00","date_gmt":"2018-10-07T15:48:00","guid":{"rendered":"http:\/\/www.c-intereg.es\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/"},"modified":"2019-03-15T13:41:46","modified_gmt":"2019-03-15T12:41:46","slug":"cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana","status":"publish","type":"post","link":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/","title":{"rendered":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana?"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;2\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3338&#8243; alignment=&#8221;center&#8221; animation=&#8221;Fade In&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; max_width=&#8221;100%&#8221;][vc_column_text css=&#8221;.vc_custom_1545324509511{margin-top: 2.0em !important;}&#8221;]La econom\u00eda italiana lleva ya varios trimestres en el foco medi\u00e1tico. Durante la crisis, Italia fue capaz de capear el temporal sin requerir una intervenci\u00f3n general como la aplicada a Grecia, Irlanda o Portugal. Por suerte o habilidad, Italia supo tambi\u00e9n eludir una intervenci\u00f3n parcial como la sufrida por el sistema financiero espa\u00f1ol, a pesar de contar con indicadores iguales o m\u00e1s negativos. Desde entonces, la delicada situaci\u00f3n del sistema bancario italiano ha ocupado un puesto importante en el listado de riesgos sist\u00e9micos de la UE, marcando la evoluci\u00f3n de los mercados y la agenda de numerosos debates pol\u00edticos. Los \u00faltimos resultados electorales cosechados en Italia, el crecimiento de las posiciones anti-europe\u00edstas o la postura del gobierno italiano en los debates sobre pol\u00edtica migratoria han incrementado la tensi\u00f3n entre la UE e Italia. Esta tensi\u00f3n est\u00e1 dejando ya su reflejo en los indicadores de la econom\u00eda real y financiera. Tal y como muestra el Gr\u00e1fico 1, la prima de riesgo entre el bono italiano a 10 a\u00f1os y el equivalente alem\u00e1n se ha disparado recientemente por encima de los 250 puntos b\u00e1sicos, recogiendo las malas expectativas de los mercados ante la postura del gobierno italiano contraria a asumir la consolidaci\u00f3n fiscal exigida por Bruselas para los pr\u00f3ximos a\u00f1os en el marco del PEC.[\/vc_column_text][\/vc_column][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/3&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;iconsmind&#8221; url=&#8221;\/publicaciones\/actualidad\/Cuadro_La_exposicion_de_las_CCAA_a_Italia_Llano_Gallego.pdf&#8221; text=&#8221;Descargar Cuadro&#8221; icon_iconsmind=&#8221;iconsmind-Data-Download&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Este informe incluye un\u00a0an\u00e1lisis espec\u00edfico\u00a0del grado de exposici\u00f3n de cada CCAA a la econom\u00eda italiana.\u00a0Las\u00a0regiones italianas\u00a0con intensidades m\u00e1s fuertes de\u00a0compras de productos espa\u00f1oles, se concentran en\u00a0las regiones m\u00e1s pr\u00f3ximas y ricas del norte de Italia\u00a0(Lombard\u00eda, Piamonte y Veneto)\u2026<\/p>\n","protected":false},"author":1,"featured_media":3666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[69,67],"tags":[],"class_list":{"0":"post-3933","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-briefings","8":"category-featured"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg\" \/>\n<meta property=\"og:description\" content=\"Este informe incluye un\u00a0an\u00e1lisis espec\u00edfico\u00a0del grado de exposici\u00f3n de cada CCAA a la econom\u00eda italiana.\u00a0Las\u00a0regiones italianas\u00a0con intensidades m\u00e1s fuertes de\u00a0compras de productos espa\u00f1oles, se concentran en\u00a0las regiones m\u00e1s pr\u00f3ximas y ricas del norte de Italia\u00a0(Lombard\u00eda, Piamonte y Veneto)\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"C-Intereg\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-07T15:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-15T12:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"C-Intereg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"C-Intereg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\"},\"author\":{\"name\":\"C-Intereg\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\"},\"headline\":\"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana?\",\"datePublished\":\"2018-10-07T15:48:00+00:00\",\"dateModified\":\"2019-03-15T12:41:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\"},\"wordCount\":428,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png\",\"articleSection\":[\"Briefings\",\"Featured\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\",\"url\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\",\"name\":\"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg\",\"isPartOf\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png\",\"datePublished\":\"2018-10-07T15:48:00+00:00\",\"dateModified\":\"2019-03-15T12:41:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage\",\"url\":\"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png\",\"contentUrl\":\"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png\",\"width\":1140,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.c-intereg.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#website\",\"url\":\"https:\/\/www.c-intereg.es\/en\/\",\"name\":\"C-Intereg\",\"description\":\"An\u00e1lisis del comercio interregional espa\u00f1ol\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.c-intereg.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355\",\"name\":\"C-Intereg\",\"url\":\"https:\/\/www.c-intereg.es\/en\/author\/interbanner-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/","og_locale":"en_US","og_type":"article","og_title":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg","og_description":"Este informe incluye un\u00a0an\u00e1lisis espec\u00edfico\u00a0del grado de exposici\u00f3n de cada CCAA a la econom\u00eda italiana.\u00a0Las\u00a0regiones italianas\u00a0con intensidades m\u00e1s fuertes de\u00a0compras de productos espa\u00f1oles, se concentran en\u00a0las regiones m\u00e1s pr\u00f3ximas y ricas del norte de Italia\u00a0(Lombard\u00eda, Piamonte y Veneto)\u2026","og_url":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/","og_site_name":"C-Intereg","article_published_time":"2018-10-07T15:48:00+00:00","article_modified_time":"2019-03-15T12:41:46+00:00","og_image":[{"width":1140,"height":650,"url":"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png","type":"image\/png"}],"author":"C-Intereg","twitter_card":"summary_large_image","twitter_misc":{"Written by":"C-Intereg","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#article","isPartOf":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/"},"author":{"name":"C-Intereg","@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355"},"headline":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana?","datePublished":"2018-10-07T15:48:00+00:00","dateModified":"2019-03-15T12:41:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/"},"wordCount":428,"commentCount":0,"image":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png","articleSection":["Briefings","Featured"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/","url":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/","name":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana? - C-Intereg","isPartOf":{"@id":"https:\/\/www.c-intereg.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage"},"image":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png","datePublished":"2018-10-07T15:48:00+00:00","dateModified":"2019-03-15T12:41:46+00:00","author":{"@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355"},"breadcrumb":{"@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#primaryimage","url":"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png","contentUrl":"https:\/\/www.c-intereg.es\/wp-content\/uploads\/2018\/10\/Espa\u00f1a-Italia-nyhu1dndfpv0qh436c6g8tw8482ahyvnpmkx6uej50.png","width":1140,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.c-intereg.es\/en\/cuadro-como-de-expuestas-estan-las-ccaa-a-la-economia-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.c-intereg.es\/en\/"},{"@type":"ListItem","position":2,"name":"Cuadro: \u00bfC\u00f3mo de expuestas est\u00e1n las CCAA a la econom\u00eda italiana?"}]},{"@type":"WebSite","@id":"https:\/\/www.c-intereg.es\/en\/#website","url":"https:\/\/www.c-intereg.es\/en\/","name":"C-Intereg","description":"An\u00e1lisis del comercio interregional espa\u00f1ol","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.c-intereg.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.c-intereg.es\/en\/#\/schema\/person\/10a0ab81378f1dc4e12e5cb64ac80355","name":"C-Intereg","url":"https:\/\/www.c-intereg.es\/en\/author\/interbanner-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts\/3933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/comments?post=3933"}],"version-history":[{"count":1,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts\/3933\/revisions"}],"predecessor-version":[{"id":3936,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/posts\/3933\/revisions\/3936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/media\/3666"}],"wp:attachment":[{"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/media?parent=3933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/categories?post=3933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.c-intereg.es\/en\/wp-json\/wp\/v2\/tags?post=3933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}